{"id":1949,"date":"2024-03-08T15:08:21","date_gmt":"2024-03-08T14:08:21","guid":{"rendered":"https:\/\/www.pizzerieatorino.it\/?p=1949"},"modified":"2024-08-07T17:10:21","modified_gmt":"2024-08-07T15:10:21","slug":"pizzeria-a-torino-zona-san-salvario-pizzeria-fermento","status":"publish","type":"post","link":"https:\/\/www.pizzerieatorino.it\/de\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/","title":{"rendered":"Torino zona San Salvario: Pizzeria Fermento Care Passion"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1949\" class=\"elementor elementor-1949\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a7bc88 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"9a7bc88\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ceee891 elementor-widget elementor-widget-heading\" data-id=\"ceee891\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 17-06-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Pizzeria a Torino - Fermento Care Passion zona San salvario<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ef6c34 elementor-widget elementor-widget-text-editor\" data-id=\"4ef6c34\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 17-06-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Benvenuti alla\u00a0Pizzeria <a href=\"https:\/\/fermentocarepassion.com\/\" target=\"_blank\" rel=\"noopener\">Fermento Care Passion<\/a>, dove l&#8217;arte della pizza gourmet prende vita.<\/p><p>Situata in<strong> Via Belfiore 11\/B<\/strong> nel cuore di <a href=\"https:\/\/www.pizzerieatorino.it\/de\/category\/san-salvario\/\"><strong>San Salvario<\/strong><\/a> a Torino, questa pizzeria offre un&#8217;esperienza culinaria straordinaria sin dalla sua apertura nel luglio 2023.<\/p><p>Da <strong>Fermento<\/strong>, il processo di &#8220;Care Cooking&#8221; rappresenta un vero e proprio impegno verso la qualit\u00e0 e l&#8217;attenzione ai dettagli. Ogni pizza \u00e8 realizzata con ingredienti freschi e di alta qualit\u00e0, e la cura artigianale si estende dal momento della concezione del prodotto fino al servizio in tavola, garantendo un&#8217;accoglienza calorosa e un benessere gastronomico senza pari.<\/p><p>L&#8217;atmosfera accogliente e l&#8217;attenzione al cliente sono elementi distintivi di Fermento, dove ogni visita diventa un viaggio tra le tradizioni italiane arricchite da un tocco creativo. Che tu stia cercando un luogo per una serata speciale o semplicemente una pizza deliziosa, <a href=\"https:\/\/www.pizzerieatorino.it\/de\/category\/pizzerie-torino\/fermento\/\"><strong>Fermento Care Passion<\/strong> <\/a>\u00e8 la destinazione ideale per assaporare una pizza artigianale indimenticabile.<\/p><h3><span style=\"color: #4d5156; font-family: arial, sans-serif;\"><br \/>Localit\u00e0 e contatti.\u00a0<\/span><\/h3><p><span style=\"color: #4d5156; font-family: arial, sans-serif;\">Via Belfiore 11\/B, 10125\u00a0<\/span><span style=\"font-weight: bold; color: #5f6368; font-family: arial, sans-serif;\">Torino<\/span><span style=\"color: #4d5156; font-family: arial, sans-serif;\">\u00a0Italia.\u00a0<\/span><span style=\"font-weight: bold; color: #5f6368; font-family: arial, sans-serif;\">San Salvario<\/span><span style=\"color: #4d5156; font-family: arial, sans-serif;\">.<\/span><\/p><div style=\"color: #202124; font-family: arial, sans-serif; display: inline;\"><div style=\"opacity: 1; position: static; display: inline-block; color: #000000; height: auto; margin-top: -3px; overflow: hidden; transition: opacity 1s ease 0s; vertical-align: top; visibility: inherit;\"><div style=\"color: #202124; outline: 0px;\" tabindex=\"0\" role=\"button\" aria-expanded=\"true\" data-ved=\"2ahUKEwjvksq038iEAxVJgv0HHX5VAo0Q5nF6BAhQEAQ\"><div class=\"bJpcZ t-oh\" style=\"display: inline;\"><div class=\"a-h\" style=\"opacity: 1; position: static; display: inline-block; color: #000000; height: auto; margin-top: -3px; overflow: hidden; transition: opacity 1s ease 0s; vertical-align: top; visibility: inherit;\"><div class=\"vk_bk\" style=\"color: #202124; outline: 0px;\" tabindex=\"0\" role=\"button\" aria-expanded=\"true\" data-ved=\"2ahUKEwis-t6hpMuEAxX_hv0HHW0YCYQQ5nF6BAhOEAQ\"><div class=\"bJpcZ t-oh\" style=\"display: inline;\"><div class=\"a-h\" style=\"opacity: 1; position: static; display: inline-block; color: #000000; height: auto; margin-top: -3px; overflow: hidden; transition: opacity 1s ease 0s; vertical-align: top; visibility: inherit;\">\u00a0<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-caa9d79 elementor-widget elementor-widget-google_maps\" data-id=\"caa9d79\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 17-06-2024 *\/\n.elementor-widget-google_maps .elementor-widget-container{overflow:hidden}.elementor-widget-google_maps .elementor-custom-embed{line-height:0}.elementor-widget-google_maps iframe{height:300px}<\/style>\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tdata-src=\"https:\/\/maps.google.com\/maps?q=pizzeria%20fermento%20care%20passion%20torino&#038;t=m&#038;z=15&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"pizzeria fermento care passion torino\"\n\t\t\t\t\taria-label=\"pizzeria fermento care passion torino\"\n\t\t\t src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e3af46c e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"e3af46c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-83b93df elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"83b93df\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 17-06-2024 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized):not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"83b93df\" data-elementor-lightbox-title=\"IMG_7666\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg5OCwidXJsIjoiaHR0cHM6XC9cL3d3dy5waXp6ZXJpZWF0b3Jpbm8uaXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAzXC9JTUdfNzY2Ni1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6IjgzYjkzZGYifQ%3D%3D\" href=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7666-scaled.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7666-500x500.webp\" alt=\"IMG_7666\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;\" \/><noscript><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7666-500x500.webp\" alt=\"IMG_7666\" \/><\/noscript><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"83b93df\" data-elementor-lightbox-title=\"Pizza overbooking\" data-elementor-lightbox-description=\"Pizza overbooking pizzeria fermento torino\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg5NywidXJsIjoiaHR0cHM6XC9cL3d3dy5waXp6ZXJpZWF0b3Jpbm8uaXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAzXC9JTUdfNzY1OS1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6IjgzYjkzZGYifQ%3D%3D\" href=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7659-scaled.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7659-500x500.webp\" alt=\"Pizza overbooking pizzeria fermento torino\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;\" \/><noscript><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7659-500x500.webp\" alt=\"Pizza overbooking pizzeria fermento torino\" \/><\/noscript><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"83b93df\" data-elementor-lightbox-title=\"Pizza overbooking\" data-elementor-lightbox-description=\"Pizza overbooking pizzeria fermento torino\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg5NiwidXJsIjoiaHR0cHM6XC9cL3d3dy5waXp6ZXJpZWF0b3Jpbm8uaXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAzXC9JTUdfNzY1OC1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6IjgzYjkzZGYifQ%3D%3D\" href=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7658-scaled.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7658-500x500.webp\" alt=\"Pizza overbooking pizzeria fermento torino\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;\" \/><noscript><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7658-500x500.webp\" alt=\"Pizza overbooking pizzeria fermento torino\" \/><\/noscript><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"83b93df\" data-elementor-lightbox-title=\"pizza difesa francese\" data-elementor-lightbox-description=\"pizza difesa francese\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTkwMiwidXJsIjoiaHR0cHM6XC9cL3d3dy5waXp6ZXJpZWF0b3Jpbm8uaXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAzXC9waXp6YS1kaWZlc2EtZnJhbmNlc2UtMS1qcGcud2VicCIsInNsaWRlc2hvdyI6IjgzYjkzZGYifQ%3D%3D\" href=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/pizza-difesa-francese-1-jpg.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/pizza-difesa-francese-1-500x500.webp\" alt=\"pizza difesa francese\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;\" \/><noscript><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/pizza-difesa-francese-1-500x500.webp\" alt=\"pizza difesa francese\" \/><\/noscript><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"83b93df\" data-elementor-lightbox-title=\"IMG_7671\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTkwMSwidXJsIjoiaHR0cHM6XC9cL3d3dy5waXp6ZXJpZWF0b3Jpbm8uaXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAzXC9JTUdfNzY3MS1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6IjgzYjkzZGYifQ%3D%3D\" href=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7671-scaled.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7671-500x500.webp\" alt=\"IMG_7671\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;\" \/><noscript><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7671-500x500.webp\" alt=\"IMG_7671\" \/><\/noscript><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"83b93df\" data-elementor-lightbox-title=\"Pizza da fermento\" data-elementor-lightbox-description=\"Pizza da fermento\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTkwMCwidXJsIjoiaHR0cHM6XC9cL3d3dy5waXp6ZXJpZWF0b3Jpbm8uaXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAzXC9JTUdfNzY2OS1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6IjgzYjkzZGYifQ%3D%3D\" href=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7669-scaled.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7669-500x500.webp\" alt=\"Pizza da fermento\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;\" \/><noscript><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7669-500x500.webp\" alt=\"Pizza da fermento\" \/><\/noscript><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 von 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"83b93df\" data-elementor-lightbox-title=\"Pizza overbooking pizzeria fermento torino\" data-elementor-lightbox-description=\"Pizza overbooking pizzeria fermento torino\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg5NCwidXJsIjoiaHR0cHM6XC9cL3d3dy5waXp6ZXJpZWF0b3Jpbm8uaXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAzXC9JTUdfNzY0OC1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6IjgzYjkzZGYifQ%3D%3D\" href=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7648-scaled.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7648-500x500.webp\" alt=\"pizza overbooking\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;\" \/><noscript><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7648-500x500.webp\" alt=\"pizza overbooking\" \/><\/noscript><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 von 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"83b93df\" data-elementor-lightbox-title=\"IMG_7667\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg5OSwidXJsIjoiaHR0cHM6XC9cL3d3dy5waXp6ZXJpZWF0b3Jpbm8uaXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAzXC9JTUdfNzY2Ny1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6IjgzYjkzZGYifQ%3D%3D\" href=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7667-scaled.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7667-500x500.webp\" alt=\"IMG_7667\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;\" \/><noscript><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7667-500x500.webp\" alt=\"IMG_7667\" \/><\/noscript><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 von 9\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"83b93df\" data-elementor-lightbox-title=\"IMG_7647\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg5MywidXJsIjoiaHR0cHM6XC9cL3d3dy5waXp6ZXJpZWF0b3Jpbm8uaXRcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjRcLzAzXC9JTUdfNzY0Ny1zY2FsZWQud2VicCIsInNsaWRlc2hvdyI6IjgzYjkzZGYifQ%3D%3D\" href=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7647-scaled.webp\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image lazyload\" data-src=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7647-500x500.webp\" alt=\"IMG_7647\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 500px; --smush-placeholder-aspect-ratio: 500\/500;\" \/><noscript><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/IMG_7647-500x500.webp\" alt=\"IMG_7647\" \/><\/noscript><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pizzeria a Torino &#8211; Fermento Care Passion zona San salvario Benvenuti alla\u00a0Pizzeria Fermento Care Passion, dove l&#8217;arte della pizza gourmet prende vita. Situata in Via Belfiore 11\/B nel cuore di San Salvario a Torino, questa pizzeria offre un&#8217;esperienza culinaria straordinaria sin dalla sua apertura nel luglio 2023. Da Fermento, il processo di &#8220;Care Cooking&#8221; rappresenta un vero e proprio impegno verso la qualit\u00e0 e l&#8217;attenzione ai dettagli. Ogni pizza \u00e8 realizzata con ingredienti freschi e di alta qualit\u00e0, e la cura artigianale si estende dal momento della concezione del prodotto fino al servizio in tavola, garantendo un&#8217;accoglienza calorosa e un benessere gastronomico senza pari. L&#8217;atmosfera accogliente e l&#8217;attenzione al cliente sono elementi distintivi di Fermento, dove ogni visita diventa un viaggio tra le tradizioni italiane arricchite da un tocco creativo. Che tu stia cercando un luogo per una serata speciale o semplicemente una pizza deliziosa, Fermento Care Passion \u00e8 la destinazione ideale per assaporare una pizza artigianale indimenticabile. Localit\u00e0 e contatti.\u00a0 Via Belfiore 11\/B, 10125\u00a0Torino\u00a0Italia.\u00a0San Salvario. \u00a0<\/p>","protected":false},"author":1,"featured_media":1851,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[277,23],"tags":[279],"class_list":["post-1949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fermento","category-san-salvario","tag-pizzeria-fermento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v23.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Torino zona San Salvario: Pizzeria Fermento Care Passion - Pizzerie a Torino<\/title>\n<meta name=\"description\" content=\"Pizzerie a Torino | Fermento Care Passion situata in Via Belfiore 11\/B nel cuore di San Salvario a Torino, questa pizzeria...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pizzerieatorino.it\/de\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Torino zona San Salvario: Pizzeria Fermento Care Passion\" \/>\n<meta property=\"og:description\" content=\"Pizzeria a Torino - Fermento Care Passion zona San salvario Benvenuti alla\u00a0Pizzeria Fermento Care Passion, dove l&#039;arte della pizza gourmet prende\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pizzerieatorino.it\/de\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/\" \/>\n<meta property=\"og:site_name\" content=\"Pizzerie a Torino\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-08T14:08:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-07T15:10:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/Progetto-senza-titolo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"merlino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"merlino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/\"},\"author\":{\"name\":\"merlino\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/#\/schema\/person\/3d70498e56bc807b7a700e3becfc9405\"},\"headline\":\"Torino zona San Salvario: Pizzeria Fermento Care Passion\",\"datePublished\":\"2024-03-08T14:08:21+00:00\",\"dateModified\":\"2024-08-07T15:10:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/\"},\"wordCount\":174,\"publisher\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/Progetto-senza-titolo.png\",\"keywords\":[\"pizzeria fermento\"],\"articleSection\":[\"Fermento\",\"San Salvario\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/\",\"url\":\"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/\",\"name\":\"Torino zona San Salvario: Pizzeria Fermento Care Passion - Pizzerie a Torino\",\"isPartOf\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/Progetto-senza-titolo.png\",\"datePublished\":\"2024-03-08T14:08:21+00:00\",\"dateModified\":\"2024-08-07T15:10:21+00:00\",\"description\":\"Pizzerie a Torino | Fermento Care Passion situata in Via Belfiore 11\/B nel cuore di San Salvario a Torino, questa pizzeria...\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#primaryimage\",\"url\":\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/Progetto-senza-titolo.png\",\"contentUrl\":\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/Progetto-senza-titolo.png\",\"width\":800,\"height\":500,\"caption\":\"Fermento care passion - pizzerie a torino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pizzerieatorino.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Torino zona San Salvario: Pizzeria Fermento Care Passion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/#website\",\"url\":\"https:\/\/www.pizzerieatorino.it\/\",\"name\":\"Pizzerie a Torino\",\"description\":\"Pizzerie a Torino\",\"publisher\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/#organization\"},\"alternateName\":\"Pizzerie a Torino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pizzerieatorino.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\/\/www.pizzerieatorino.it\/#organization\",\"name\":\"Pizzerie a Torino\",\"alternateName\":\"Pizzerie a Torino\",\"url\":\"https:\/\/www.pizzerieatorino.it\/\",\"logo\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#local-main-organization-logo\"},\"sameAs\":[\"https:\/\/www.instagram.com\/pizzanordpassion\/\"],\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/#\/schema\/person\/3d70498e56bc807b7a700e3becfc9405\",\"name\":\"merlino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d29ad99826a18ab7bb69e326c6d275a229efcfb42bd8a12de4834e2698e9b90d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d29ad99826a18ab7bb69e326c6d275a229efcfb42bd8a12de4834e2698e9b90d?s=96&d=mm&r=g\",\"caption\":\"merlino\"},\"sameAs\":[\"https:\/\/www.pizzerieatorino.it\"],\"url\":\"https:\/\/www.pizzerieatorino.it\/de\/author\/merlino\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#local-main-organization-logo\",\"url\":\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/06\/cropped-Calcio-a-5-1.png\",\"contentUrl\":\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/06\/cropped-Calcio-a-5-1.png\",\"width\":512,\"height\":512,\"caption\":\"Pizzerie a Torino\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Torino zona San Salvario: Pizzeria Fermento Care Passion - Pizzerie a Torino","description":"Pizzerie a Torino | Fermento Care Passion situata in Via Belfiore 11\/B nel cuore di San Salvario a Torino, questa pizzeria...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pizzerieatorino.it\/de\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/","og_locale":"de_DE","og_type":"article","og_title":"Torino zona San Salvario: Pizzeria Fermento Care Passion","og_description":"Pizzeria a Torino - Fermento Care Passion zona San salvario Benvenuti alla\u00a0Pizzeria Fermento Care Passion, dove l'arte della pizza gourmet prende","og_url":"https:\/\/www.pizzerieatorino.it\/de\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/","og_site_name":"Pizzerie a Torino","article_published_time":"2024-03-08T14:08:21+00:00","article_modified_time":"2024-08-07T15:10:21+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/Progetto-senza-titolo.png","type":"image\/png"}],"author":"merlino","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"merlino","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#article","isPartOf":{"@id":"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/"},"author":{"name":"merlino","@id":"https:\/\/www.pizzerieatorino.it\/#\/schema\/person\/3d70498e56bc807b7a700e3becfc9405"},"headline":"Torino zona San Salvario: Pizzeria Fermento Care Passion","datePublished":"2024-03-08T14:08:21+00:00","dateModified":"2024-08-07T15:10:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/"},"wordCount":174,"publisher":{"@id":"https:\/\/www.pizzerieatorino.it\/#organization"},"image":{"@id":"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/Progetto-senza-titolo.png","keywords":["pizzeria fermento"],"articleSection":["Fermento","San Salvario"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/","url":"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/","name":"Torino zona San Salvario: Pizzeria Fermento Care Passion - Pizzerie a Torino","isPartOf":{"@id":"https:\/\/www.pizzerieatorino.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#primaryimage"},"image":{"@id":"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/Progetto-senza-titolo.png","datePublished":"2024-03-08T14:08:21+00:00","dateModified":"2024-08-07T15:10:21+00:00","description":"Pizzerie a Torino | Fermento Care Passion situata in Via Belfiore 11\/B nel cuore di San Salvario a Torino, questa pizzeria...","breadcrumb":{"@id":"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#primaryimage","url":"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/Progetto-senza-titolo.png","contentUrl":"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/Progetto-senza-titolo.png","width":800,"height":500,"caption":"Fermento care passion - pizzerie a torino"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pizzerieatorino.it\/"},{"@type":"ListItem","position":2,"name":"Torino zona San Salvario: Pizzeria Fermento Care Passion"}]},{"@type":"WebSite","@id":"https:\/\/www.pizzerieatorino.it\/#website","url":"https:\/\/www.pizzerieatorino.it\/","name":"Pizzerie a Torino","description":"Pizzerie a Torino","publisher":{"@id":"https:\/\/www.pizzerieatorino.it\/#organization"},"alternateName":"Pizzerie a Torino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pizzerieatorino.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Organization","Place"],"@id":"https:\/\/www.pizzerieatorino.it\/#organization","name":"Pizzerie a Torino","alternateName":"Pizzerie a Torino","url":"https:\/\/www.pizzerieatorino.it\/","logo":{"@id":"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#local-main-organization-logo"},"sameAs":["https:\/\/www.instagram.com\/pizzanordpassion\/"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.pizzerieatorino.it\/#\/schema\/person\/3d70498e56bc807b7a700e3becfc9405","name":"merlino","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.pizzerieatorino.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d29ad99826a18ab7bb69e326c6d275a229efcfb42bd8a12de4834e2698e9b90d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d29ad99826a18ab7bb69e326c6d275a229efcfb42bd8a12de4834e2698e9b90d?s=96&d=mm&r=g","caption":"merlino"},"sameAs":["https:\/\/www.pizzerieatorino.it"],"url":"https:\/\/www.pizzerieatorino.it\/de\/author\/merlino\/"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.pizzerieatorino.it\/pizzeria-a-torino-zona-san-salvario-pizzeria-fermento\/#local-main-organization-logo","url":"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/06\/cropped-Calcio-a-5-1.png","contentUrl":"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/06\/cropped-Calcio-a-5-1.png","width":512,"height":512,"caption":"Pizzerie a Torino"}]}},"_links":{"self":[{"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/posts\/1949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/comments?post=1949"}],"version-history":[{"count":19,"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/posts\/1949\/revisions"}],"predecessor-version":[{"id":3366,"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/posts\/1949\/revisions\/3366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/media\/1851"}],"wp:attachment":[{"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/media?parent=1949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/categories?post=1949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/tags?post=1949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}