{"id":2690,"date":"2024-05-20T09:51:26","date_gmt":"2024-05-20T07:51:26","guid":{"rendered":"https:\/\/www.pizzerieatorino.it\/?p=2690"},"modified":"2024-05-20T09:55:13","modified_gmt":"2024-05-20T07:55:13","slug":"torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi","status":"publish","type":"post","link":"https:\/\/www.pizzerieatorino.it\/de\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/","title":{"rendered":"Torino zona Madonna del pilone: Pizzeria P\u00e0 e Fioi"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"2690\" class=\"elementor elementor-2690\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24c0666b0 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"24c0666b0\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ec47e77\" data-id=\"2ec47e77\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-559d7b0c elementor-widget elementor-widget-heading\" data-id=\"559d7b0c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 17-06-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Pizzeria: Pizzeria P\u00e0 e Fioi<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c142d6e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"4c142d6e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-79b5295d\" data-id=\"79b5295d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc27256 elementor-widget elementor-widget-google_maps\" data-id=\"bc27256\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 17-06-2024 *\/\n.elementor-widget-google_maps .elementor-widget-container{overflow:hidden}.elementor-widget-google_maps .elementor-custom-embed{line-height:0}.elementor-widget-google_maps iframe{height:300px}<\/style>\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tdata-src=\"https:\/\/maps.google.com\/maps?q=Pizzeria%20P%C3%A0%20e%20Fioi%20torino&#038;t=m&#038;z=15&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Pizzeria P\u00e0 e Fioi torino\"\n\t\t\t\t\taria-label=\"Pizzeria P\u00e0 e Fioi torino\"\n\t\t\t src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5b3964b5\" data-id=\"5b3964b5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-568aa6d1 elementor-widget elementor-widget-heading\" data-id=\"568aa6d1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pizzeria a Torino -  Pizzeria P\u00e0 e Fioi<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e0ab825 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7e0ab825\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 17-06-2024 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-block-end:0;flex-grow:1;border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider--element-align-start .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-start .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-start .elementor-divider__element{margin-inline-start:0}.elementor-widget-divider--element-align-end .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-end .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-end .elementor-divider__element{margin-inline-end:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-347df7c0 elementor-widget elementor-widget-text-editor\" data-id=\"347df7c0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 17-06-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Pizzeria P\u00e0 e Fioi e pizza<\/p><p>Localit\u00e0 e contatti<\/p><p>Corso casale, 100D,\u00a0 Torino TO Torino Crocetta.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pizzeria: Pizzeria P\u00e0 e Fioi Pizzeria a Torino &#8211; Pizzeria P\u00e0 e Fioi Pizzeria P\u00e0 e Fioi e pizza Localit\u00e0 e contatti Corso casale, 100D,\u00a0 Torino TO Torino Crocetta.<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[226,282],"tags":[389,182],"class_list":["post-2690","post","type-post","status-publish","format-standard","hentry","category-madonna-del-pilone","category-pizzerie-torino","tag-pizzeria-pa-e-fioi","tag-torino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v23.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Torino zona Madonna del pilone: Pizzeria P\u00e0 e Fioi - Pizzerie a Torino<\/title>\n<meta name=\"description\" content=\"Pizzerie a Torino | Pizzeria: Pizzeria P\u00e0 e Fioi Pizzeria a Torino - Pizzeria P\u00e0 e Fioi Pizzeria P\u00e0 e Fioi e pizzaLocalit\u00e0 e contattiCorso casale, 100D,\u00a0 Torino TO Torino\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pizzerieatorino.it\/de\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Torino zona Madonna del pilone: Pizzeria P\u00e0 e Fioi\" \/>\n<meta property=\"og:description\" content=\"Pizzeria: Pizzeria P\u00e0 e Fioi Pizzeria a Torino - Pizzeria P\u00e0 e Fioi Pizzeria P\u00e0 e Fioi e pizzaLocalit\u00e0 e contattiCorso casale, 100D,\u00a0 Torino TO Torino\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pizzerieatorino.it\/de\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/\" \/>\n<meta property=\"og:site_name\" content=\"Pizzerie a Torino\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-20T07:51:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-20T07:55:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/Rosso-Giallo-Moderno-Illustrato-Pizzeria-Logo-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"186\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"merlino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"merlino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/\"},\"author\":{\"name\":\"merlino\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/#\/schema\/person\/3d70498e56bc807b7a700e3becfc9405\"},\"headline\":\"Torino zona Madonna del pilone: Pizzeria P\u00e0 e Fioi\",\"datePublished\":\"2024-05-20T07:51:26+00:00\",\"dateModified\":\"2024-05-20T07:55:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/\"},\"wordCount\":38,\"publisher\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/#organization\"},\"keywords\":[\"Pizzeria P\u00e0 e Fioi\",\"Torino\"],\"articleSection\":[\"Madonna del pilone\",\"Pizzerie torino\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/\",\"url\":\"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/\",\"name\":\"Torino zona Madonna del pilone: Pizzeria P\u00e0 e Fioi - Pizzerie a Torino\",\"isPartOf\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/#website\"},\"datePublished\":\"2024-05-20T07:51:26+00:00\",\"dateModified\":\"2024-05-20T07:55:13+00:00\",\"description\":\"Pizzerie a Torino | Pizzeria: Pizzeria P\u00e0 e Fioi Pizzeria a Torino - Pizzeria P\u00e0 e Fioi Pizzeria P\u00e0 e Fioi e pizzaLocalit\u00e0 e contattiCorso casale, 100D,\u00a0 Torino TO Torino\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pizzerieatorino.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Torino zona Madonna del pilone: Pizzeria P\u00e0 e Fioi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/#website\",\"url\":\"https:\/\/www.pizzerieatorino.it\/\",\"name\":\"Pizzerie a Torino\",\"description\":\"Pizzerie a Torino\",\"publisher\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/#organization\"},\"alternateName\":\"Pizzerie a Torino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pizzerieatorino.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\/\/www.pizzerieatorino.it\/#organization\",\"name\":\"Pizzerie a Torino\",\"alternateName\":\"Pizzerie a Torino\",\"url\":\"https:\/\/www.pizzerieatorino.it\/\",\"logo\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/#local-main-organization-logo\"},\"sameAs\":[\"https:\/\/www.instagram.com\/pizzanordpassion\/\"],\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/#\/schema\/person\/3d70498e56bc807b7a700e3becfc9405\",\"name\":\"merlino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d29ad99826a18ab7bb69e326c6d275a229efcfb42bd8a12de4834e2698e9b90d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d29ad99826a18ab7bb69e326c6d275a229efcfb42bd8a12de4834e2698e9b90d?s=96&d=mm&r=g\",\"caption\":\"merlino\"},\"sameAs\":[\"https:\/\/www.pizzerieatorino.it\"],\"url\":\"https:\/\/www.pizzerieatorino.it\/de\/author\/merlino\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/#local-main-organization-logo\",\"url\":\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/06\/cropped-Calcio-a-5-1.png\",\"contentUrl\":\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/06\/cropped-Calcio-a-5-1.png\",\"width\":512,\"height\":512,\"caption\":\"Pizzerie a Torino\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Torino zona Madonna del pilone: Pizzeria P\u00e0 e Fioi - Pizzerie a Torino","description":"Pizzerie a Torino | Pizzeria: Pizzeria P\u00e0 e Fioi Pizzeria a Torino - Pizzeria P\u00e0 e Fioi Pizzeria P\u00e0 e Fioi e pizzaLocalit\u00e0 e contattiCorso casale, 100D,\u00a0 Torino TO Torino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pizzerieatorino.it\/de\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/","og_locale":"de_DE","og_type":"article","og_title":"Torino zona Madonna del pilone: Pizzeria P\u00e0 e Fioi","og_description":"Pizzeria: Pizzeria P\u00e0 e Fioi Pizzeria a Torino - Pizzeria P\u00e0 e Fioi Pizzeria P\u00e0 e Fioi e pizzaLocalit\u00e0 e contattiCorso casale, 100D,\u00a0 Torino TO Torino","og_url":"https:\/\/www.pizzerieatorino.it\/de\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/","og_site_name":"Pizzerie a Torino","article_published_time":"2024-05-20T07:51:26+00:00","article_modified_time":"2024-05-20T07:55:13+00:00","og_image":[{"width":500,"height":186,"url":"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/Rosso-Giallo-Moderno-Illustrato-Pizzeria-Logo-1.png","type":"image\/png"}],"author":"merlino","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"merlino","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/#article","isPartOf":{"@id":"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/"},"author":{"name":"merlino","@id":"https:\/\/www.pizzerieatorino.it\/#\/schema\/person\/3d70498e56bc807b7a700e3becfc9405"},"headline":"Torino zona Madonna del pilone: Pizzeria P\u00e0 e Fioi","datePublished":"2024-05-20T07:51:26+00:00","dateModified":"2024-05-20T07:55:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/"},"wordCount":38,"publisher":{"@id":"https:\/\/www.pizzerieatorino.it\/#organization"},"keywords":["Pizzeria P\u00e0 e Fioi","Torino"],"articleSection":["Madonna del pilone","Pizzerie torino"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/","url":"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/","name":"Torino zona Madonna del pilone: Pizzeria P\u00e0 e Fioi - Pizzerie a Torino","isPartOf":{"@id":"https:\/\/www.pizzerieatorino.it\/#website"},"datePublished":"2024-05-20T07:51:26+00:00","dateModified":"2024-05-20T07:55:13+00:00","description":"Pizzerie a Torino | Pizzeria: Pizzeria P\u00e0 e Fioi Pizzeria a Torino - Pizzeria P\u00e0 e Fioi Pizzeria P\u00e0 e Fioi e pizzaLocalit\u00e0 e contattiCorso casale, 100D,\u00a0 Torino TO Torino","breadcrumb":{"@id":"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pizzerieatorino.it\/"},{"@type":"ListItem","position":2,"name":"Torino zona Madonna del pilone: Pizzeria P\u00e0 e Fioi"}]},{"@type":"WebSite","@id":"https:\/\/www.pizzerieatorino.it\/#website","url":"https:\/\/www.pizzerieatorino.it\/","name":"Pizzerie a Torino","description":"Pizzerie a Torino","publisher":{"@id":"https:\/\/www.pizzerieatorino.it\/#organization"},"alternateName":"Pizzerie a Torino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pizzerieatorino.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Organization","Place"],"@id":"https:\/\/www.pizzerieatorino.it\/#organization","name":"Pizzerie a Torino","alternateName":"Pizzerie a Torino","url":"https:\/\/www.pizzerieatorino.it\/","logo":{"@id":"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/#local-main-organization-logo"},"sameAs":["https:\/\/www.instagram.com\/pizzanordpassion\/"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.pizzerieatorino.it\/#\/schema\/person\/3d70498e56bc807b7a700e3becfc9405","name":"merlino","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.pizzerieatorino.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d29ad99826a18ab7bb69e326c6d275a229efcfb42bd8a12de4834e2698e9b90d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d29ad99826a18ab7bb69e326c6d275a229efcfb42bd8a12de4834e2698e9b90d?s=96&d=mm&r=g","caption":"merlino"},"sameAs":["https:\/\/www.pizzerieatorino.it"],"url":"https:\/\/www.pizzerieatorino.it\/de\/author\/merlino\/"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.pizzerieatorino.it\/torino-zona-madonna-del-pilone-pizzeria-pa-e-fioi\/#local-main-organization-logo","url":"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/06\/cropped-Calcio-a-5-1.png","contentUrl":"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/06\/cropped-Calcio-a-5-1.png","width":512,"height":512,"caption":"Pizzerie a Torino"}]}},"_links":{"self":[{"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/posts\/2690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/comments?post=2690"}],"version-history":[{"count":4,"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/posts\/2690\/revisions"}],"predecessor-version":[{"id":2694,"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/posts\/2690\/revisions\/2694"}],"wp:attachment":[{"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/media?parent=2690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/categories?post=2690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pizzerieatorino.it\/de\/wp-json\/wp\/v2\/tags?post=2690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}