{"id":1551,"date":"2024-03-04T11:53:57","date_gmt":"2024-03-04T10:53:57","guid":{"rendered":"https:\/\/www.pizzerieatorino.it\/?p=1551"},"modified":"2024-06-04T12:32:15","modified_gmt":"2024-06-04T10:32:15","slug":"elenco-pizzerie-a-torino-zona-lucento","status":"publish","type":"post","link":"https:\/\/www.pizzerieatorino.it\/fr\/elenco-pizzerie-a-torino-zona-lucento\/","title":{"rendered":"Elenco Pizzerie a Torino Zona Lucento"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1551\" class=\"elementor elementor-1551\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-406162f4 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"406162f4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c875f4 elementor-widget elementor-widget-heading\" data-id=\"4c875f4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 17-06-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Introduzione: Pizzerie a Torino Zona Lucento<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6137d17f elementor-widget elementor-widget-text-editor\" data-id=\"6137d17f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 17-06-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Se ti trovi nella zona Lucento a Torino e hai voglia di una deliziosa pizza, sei nel posto giusto! Questa zona offre una variet\u00e0 di pizzerie, ognuna con il suo stile unico e i suoi sapori irresistibili. Ecco un elenco di alcune delle migliori pizzerie della zona:<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2feb08f elementor-widget elementor-widget-heading\" data-id=\"2feb08f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">liste des pizz\u00e9rias<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e6e317 elementor-widget elementor-widget-text-editor\" data-id=\"9e6e317\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<table><tbody><tr><th>Pizzeria<\/th><th>Indirizzo<\/th><th>Dettaglio<\/th><\/tr><tr><td>Pizze e Delizie<\/td><td>Via Foglizzo, 8<\/td><td><a href=\"https:\/\/www.pizzerieatorino.it\/fr\/torino-zona-lucento-pizze-e-delizie-2\/\"><b>Dettaglio<\/b><\/a><\/td><\/tr><tr><td>Presto Pizza<\/td><td>Via Lucento, 114<\/td><td><a href=\"https:\/\/www.pizzerieatorino.it\/fr\/torino-zona-lucento-presto-pizza\/\"><b>Dettaglio<\/b><\/a><\/td><\/tr><tr><td>Pizzeria Joso<\/td><td>Via Lucento<\/td><td><a href=\"https:\/\/www.pizzerieatorino.it\/fr\/torino-zona-lucento-pizzeria-joso\/\"><b>Dettaglio<\/b><\/a><\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22a09cd elementor-widget elementor-widget-text-editor\" data-id=\"22a09cd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align);\">Queste sono solo alcune delle fantastiche <a href=\"https:\/\/www.pizzerieatorino.it\/fr\/\">pizz\u00e9rias<\/a> che puoi trovare nella zona Lucento a Torino. Scegli quella che fa per te e goditi un&#8217;esperienza gastronomica indimenticabile!<\/span><\/p><blockquote><p>\u00a0<span style=\"color: #0d0d0d; font-family: S\u00f6hne, ui-sans-serif, system-ui, -apple-system, 'Segoe UI', Roboto, Ubuntu, Cantarell, 'Noto Sans', sans-serif, 'Helvetica Neue', Arial, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji'; font-size: 16px; white-space-collapse: preserve; font-weight: var( --e-global-typography-text-font-weight ); text-align: var(--text-align); background-color: #ffffff;\">Ci sono poche cose nella vita che una pizza calda non possa risolvere<\/span><\/p><\/blockquote>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Introduzione: Pizzerie a Torino Zona Lucento Se ti trovi nella zona Lucento a Torino e hai voglia di una deliziosa pizza, sei nel posto giusto! Questa zona offre una variet\u00e0 di pizzerie, ognuna con il suo stile unico e i suoi sapori irresistibili. Ecco un elenco di alcune delle migliori pizzerie della zona: Elenco delle pizzerie: Pizzeria Indirizzo Dettaglio Pizze e Delizie Via Foglizzo, 8 Dettaglio Presto Pizza Via Lucento, 114 Dettaglio Pizzeria Joso Via Lucento Dettaglio Queste sono solo alcune delle fantastiche pizzerie che puoi trovare nella zona Lucento a Torino. Scegli quella che fa per te e goditi un&#8217;esperienza gastronomica indimenticabile! \u00a0Ci sono poche cose nella vita che una pizza calda non possa risolvere<\/p>","protected":false},"author":1,"featured_media":1684,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"wprm-recipe-roundup-name":"","wprm-recipe-roundup-description":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[225],"tags":[182,353],"class_list":["post-1551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lucento","tag-torino","tag-zona-lucento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.1 (Yoast SEO v23.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Elenco Pizzerie a Torino Zona Lucento - Pizzerie a Torino<\/title>\n<meta name=\"description\" content=\"Pizzerie a Torino | Introduzione: Pizzerie a Torino Zona Lucento Se ti trovi nella zona Lucento a Torino e hai voglia di una deliziosa pizza, sei nel posto giusto! Questa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pizzerieatorino.it\/fr\/elenco-pizzerie-a-torino-zona-lucento\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elenco Pizzerie a Torino Zona Lucento\" \/>\n<meta property=\"og:description\" content=\"Introduzione: Pizzerie a Torino Zona Lucento Se ti trovi nella zona Lucento a Torino e hai voglia di una deliziosa pizza, sei nel posto giusto! Questa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pizzerieatorino.it\/fr\/elenco-pizzerie-a-torino-zona-lucento\/\" \/>\n<meta property=\"og:site_name\" content=\"Pizzerie a Torino\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-04T10:53:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-04T10:32:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/pizza-zona-lucento-e1709719493988.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"694\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"merlino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"merlino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/\"},\"author\":{\"name\":\"merlino\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/#\/schema\/person\/3d70498e56bc807b7a700e3becfc9405\"},\"headline\":\"Elenco Pizzerie a Torino Zona Lucento\",\"datePublished\":\"2024-03-04T10:53:57+00:00\",\"dateModified\":\"2024-06-04T10:32:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/\"},\"wordCount\":120,\"publisher\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/pizza-zona-lucento-e1709719493988.jpg\",\"keywords\":[\"Torino\",\"zona lucento\"],\"articleSection\":[\"Lucento\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/\",\"url\":\"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/\",\"name\":\"Elenco Pizzerie a Torino Zona Lucento - Pizzerie a Torino\",\"isPartOf\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/pizza-zona-lucento-e1709719493988.jpg\",\"datePublished\":\"2024-03-04T10:53:57+00:00\",\"dateModified\":\"2024-06-04T10:32:15+00:00\",\"description\":\"Pizzerie a Torino | Introduzione: Pizzerie a Torino Zona Lucento Se ti trovi nella zona Lucento a Torino e hai voglia di una deliziosa pizza, sei nel posto giusto! Questa\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#primaryimage\",\"url\":\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/pizza-zona-lucento-e1709719493988.jpg\",\"contentUrl\":\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/pizza-zona-lucento-e1709719493988.jpg\",\"width\":1920,\"height\":694,\"caption\":\"pizza zona lucento pizzerie a torino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pizzerieatorino.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elenco Pizzerie a Torino Zona Lucento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/#website\",\"url\":\"https:\/\/www.pizzerieatorino.it\/\",\"name\":\"Pizzerie a Torino\",\"description\":\"Pizzerie a Torino\",\"publisher\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/#organization\"},\"alternateName\":\"Pizzerie a Torino\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pizzerieatorino.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\/\/www.pizzerieatorino.it\/#organization\",\"name\":\"Pizzerie a Torino\",\"alternateName\":\"Pizzerie a Torino\",\"url\":\"https:\/\/www.pizzerieatorino.it\/\",\"logo\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#local-main-organization-logo\"},\"sameAs\":[\"https:\/\/www.instagram.com\/pizzanordpassion\/\"],\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/#\/schema\/person\/3d70498e56bc807b7a700e3becfc9405\",\"name\":\"merlino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d29ad99826a18ab7bb69e326c6d275a229efcfb42bd8a12de4834e2698e9b90d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d29ad99826a18ab7bb69e326c6d275a229efcfb42bd8a12de4834e2698e9b90d?s=96&d=mm&r=g\",\"caption\":\"merlino\"},\"sameAs\":[\"https:\/\/www.pizzerieatorino.it\"],\"url\":\"https:\/\/www.pizzerieatorino.it\/fr\/author\/merlino\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#local-main-organization-logo\",\"url\":\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/06\/cropped-Calcio-a-5-1.png\",\"contentUrl\":\"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/06\/cropped-Calcio-a-5-1.png\",\"width\":512,\"height\":512,\"caption\":\"Pizzerie a Torino\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Elenco Pizzerie a Torino Zona Lucento - Pizzerie a Torino","description":"Pizzerie a Torino | Introduzione: Pizzerie a Torino Zona Lucento Se ti trovi nella zona Lucento a Torino e hai voglia di una deliziosa pizza, sei nel posto giusto! Questa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pizzerieatorino.it\/fr\/elenco-pizzerie-a-torino-zona-lucento\/","og_locale":"fr_FR","og_type":"article","og_title":"Elenco Pizzerie a Torino Zona Lucento","og_description":"Introduzione: Pizzerie a Torino Zona Lucento Se ti trovi nella zona Lucento a Torino e hai voglia di una deliziosa pizza, sei nel posto giusto! Questa","og_url":"https:\/\/www.pizzerieatorino.it\/fr\/elenco-pizzerie-a-torino-zona-lucento\/","og_site_name":"Pizzerie a Torino","article_published_time":"2024-03-04T10:53:57+00:00","article_modified_time":"2024-06-04T10:32:15+00:00","og_image":[{"width":1920,"height":694,"url":"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/pizza-zona-lucento-e1709719493988.jpg","type":"image\/jpeg"}],"author":"merlino","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"merlino","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#article","isPartOf":{"@id":"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/"},"author":{"name":"merlino","@id":"https:\/\/www.pizzerieatorino.it\/#\/schema\/person\/3d70498e56bc807b7a700e3becfc9405"},"headline":"Elenco Pizzerie a Torino Zona Lucento","datePublished":"2024-03-04T10:53:57+00:00","dateModified":"2024-06-04T10:32:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/"},"wordCount":120,"publisher":{"@id":"https:\/\/www.pizzerieatorino.it\/#organization"},"image":{"@id":"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/pizza-zona-lucento-e1709719493988.jpg","keywords":["Torino","zona lucento"],"articleSection":["Lucento"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/","url":"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/","name":"Elenco Pizzerie a Torino Zona Lucento - Pizzerie a Torino","isPartOf":{"@id":"https:\/\/www.pizzerieatorino.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#primaryimage"},"image":{"@id":"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/pizza-zona-lucento-e1709719493988.jpg","datePublished":"2024-03-04T10:53:57+00:00","dateModified":"2024-06-04T10:32:15+00:00","description":"Pizzerie a Torino | Introduzione: Pizzerie a Torino Zona Lucento Se ti trovi nella zona Lucento a Torino e hai voglia di una deliziosa pizza, sei nel posto giusto! Questa","breadcrumb":{"@id":"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#primaryimage","url":"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/pizza-zona-lucento-e1709719493988.jpg","contentUrl":"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/03\/pizza-zona-lucento-e1709719493988.jpg","width":1920,"height":694,"caption":"pizza zona lucento pizzerie a torino"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pizzerieatorino.it\/"},{"@type":"ListItem","position":2,"name":"Elenco Pizzerie a Torino Zona Lucento"}]},{"@type":"WebSite","@id":"https:\/\/www.pizzerieatorino.it\/#website","url":"https:\/\/www.pizzerieatorino.it\/","name":"Pizzerie a Torino","description":"Pizzerie a Torino","publisher":{"@id":"https:\/\/www.pizzerieatorino.it\/#organization"},"alternateName":"Pizzerie a Torino","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pizzerieatorino.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Organization","Place"],"@id":"https:\/\/www.pizzerieatorino.it\/#organization","name":"Pizzerie a Torino","alternateName":"Pizzerie a Torino","url":"https:\/\/www.pizzerieatorino.it\/","logo":{"@id":"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#local-main-organization-logo"},"sameAs":["https:\/\/www.instagram.com\/pizzanordpassion\/"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.pizzerieatorino.it\/#\/schema\/person\/3d70498e56bc807b7a700e3becfc9405","name":"merlino","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.pizzerieatorino.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d29ad99826a18ab7bb69e326c6d275a229efcfb42bd8a12de4834e2698e9b90d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d29ad99826a18ab7bb69e326c6d275a229efcfb42bd8a12de4834e2698e9b90d?s=96&d=mm&r=g","caption":"merlino"},"sameAs":["https:\/\/www.pizzerieatorino.it"],"url":"https:\/\/www.pizzerieatorino.it\/fr\/author\/merlino\/"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.pizzerieatorino.it\/elenco-pizzerie-a-torino-zona-lucento\/#local-main-organization-logo","url":"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/06\/cropped-Calcio-a-5-1.png","contentUrl":"https:\/\/www.pizzerieatorino.it\/wp-content\/uploads\/2024\/06\/cropped-Calcio-a-5-1.png","width":512,"height":512,"caption":"Pizzerie a Torino"}]}},"_links":{"self":[{"href":"https:\/\/www.pizzerieatorino.it\/fr\/wp-json\/wp\/v2\/posts\/1551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pizzerieatorino.it\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pizzerieatorino.it\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pizzerieatorino.it\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pizzerieatorino.it\/fr\/wp-json\/wp\/v2\/comments?post=1551"}],"version-history":[{"count":12,"href":"https:\/\/www.pizzerieatorino.it\/fr\/wp-json\/wp\/v2\/posts\/1551\/revisions"}],"predecessor-version":[{"id":3004,"href":"https:\/\/www.pizzerieatorino.it\/fr\/wp-json\/wp\/v2\/posts\/1551\/revisions\/3004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pizzerieatorino.it\/fr\/wp-json\/wp\/v2\/media\/1684"}],"wp:attachment":[{"href":"https:\/\/www.pizzerieatorino.it\/fr\/wp-json\/wp\/v2\/media?parent=1551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pizzerieatorino.it\/fr\/wp-json\/wp\/v2\/categories?post=1551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pizzerieatorino.it\/fr\/wp-json\/wp\/v2\/tags?post=1551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}